{"id":77697,"date":"2018-04-02T15:52:48","date_gmt":"2018-04-02T18:52:48","guid":{"rendered":"https:\/\/www.fraterinternacional.org\/?p=77697"},"modified":"2018-04-02T15:52:48","modified_gmt":"2018-04-02T18:52:48","slug":"mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena","status":"publish","type":"post","link":"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/","title":{"rendered":"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_04.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-77681 alignleft\" src=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_04-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_04-169x300.jpg 169w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_04-200x356.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_04.jpg 388w\" sizes=\"(max-width: 169px) 100vw, 169px\" \/><\/a>El grupo <a href=\"http:\/\/www.fraterinternacional.org\/es\/red-luz\/\">Red-Luz<\/a> del Paraguay llev\u00f3 a cabo el Sexto Encuentro de la <a href=\"http:\/\/www.fraterinternacional.org\/es\/campanhas-ffhi\/mision-paraguay\/?portfolioCats=190\">Misi\u00f3n Paraguay<\/a> \u201cDespertando Semillas\u201d, en uni\u00f3n con la Consciencia Ind\u00edgena. La actividad se desarroll\u00f3 el fin de semana del 3 y 4 de marzo pasados. Cont\u00f3 con la participaci\u00f3n de 17 colaboradores de la Red-Luz de Paraguay, Argentina y Brasil.<\/p>\n<p style=\"text-align: justify;\">Los voluntarios visitaron dos comunidades abor\u00edgenes del departamento de Alto Paran\u00e1, a 320 kil\u00f3metros al este de Asunci\u00f3n, la capital del pa\u00eds. El primer d\u00eda estuvieron en una aldea Mbya- Guaran\u00ed localizada dentro del Parque Mois\u00e9s Bertoni, en el distrito de Presidente Franco, y el segundo d\u00eda, en la aldea Mbya-Guaran\u00ed \u201cYbu Pora Renda\u201d, precario asentamiento emplazado en Ciudad del Este.<\/p>\n<p style=\"text-align: justify;\">En la comunidad ind\u00edgena Puerto Bertoni, los visitantes interactuaron con los nativos por medio de diversos servicios: una m\u00e9dica brind\u00f3 atenciones de salud, un voluntario argentino coordin\u00f3 la atenci\u00f3n veterinaria de perros y gatos mientras otros ofrecieron cortes de pelo para los varones y lavado de cabeza y peinado para las mujeres.\u00a0 El domingo 4, los voluntarios prestaron los mismos servicios en la aldea Ybu Pora Renda de Ciudad del Este.<\/p>\n<p><strong>Donaciones<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_03.jpg\"><img decoding=\"async\" class=\"alignright size-medium wp-image-77678\" src=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_03-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_03-200x112.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_03-300x169.jpg 300w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_03-400x225.jpg 400w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_03-600x337.jpg 600w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_03.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En ambas comunidades, el grupo dej\u00f3 donaciones de alimentos, ropas y medicamentos. Entreg\u00f3 tambi\u00e9n seis ollas grandes y seis cucharones para promover la preparaci\u00f3n grupal de las comidas. Colabor\u00f3 igualmente con chapas de zinc para techar el <em>Opy<\/em> (casa de oraci\u00f3n) de una de las comunidades y don\u00f3 el importe necesario para la compra de instrumentos musicales utilizados en las ceremonias ind\u00edgenas.<\/p>\n<p style=\"text-align: justify;\">\u201cCada misi\u00f3n nos da la oportunidad de sentirnos realmente fraternos y de salir cada vez m\u00e1s enriquecidos\u201d, afirm\u00f3 Laura Robles, de Eldorado, Argentina. \u201cLa sensibilidad, humildad y uni\u00f3n entre los hermanos ind\u00edgenas de Puerto Bertoni es todo un ejemplo a seguir\u201d, dijo Azucena Cardozo, de la Red-Luz Paraguay. En t\u00e9rminos similares se expres\u00f3 Leandro, de Posadas, Argentina: \u201cEn este lugar bendecido por la naturaleza encontramos a una comunidad muy especial, llena de virtudes, que agradece con tanto amor lo poco que hacemos\u201d.<\/p>\n<p><strong>Pureza ind\u00edgena<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_06.jpg\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-77685\" src=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_06-300x222.jpg\" alt=\"\" width=\"300\" height=\"222\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_06-200x148.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_06-300x222.jpg 300w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_06-400x296.jpg 400w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_06-600x444.jpg 600w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_06.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u201cEsta experiencia me toc\u00f3 profundamente, sentir la pureza que conservan hasta los d\u00edas de hoy, a pesar de las condiciones en las que viven, con tantas necesidades\u201d, sintetiz\u00f3 Guillermo, de provincia de Chaco, Argentina. \u201cSiento que en cada misi\u00f3n compensamos en algo todo el da\u00f1o, discriminaci\u00f3n e indiferencia con los hermanos ind\u00edgenas\u201d, manifest\u00f3 Adriana Vallet, de Paraguay.<\/p>\n<p style=\"text-align: justify;\">La Misi\u00f3n Paraguay forma parte de la <a href=\"http:\/\/www.fraterinternacional.org\/es\/campanhas-ffhi\/mision-pueblos-originarios\/?portfolioCats=185\">Misi\u00f3n junto a los Pueblos Originarios<\/a>, una campa\u00f1a de la <strong>Fraternidade \u2013 Federaci\u00f3n Humanitaria Internacional<\/strong>. Comenz\u00f3 en junio de 2016, cuando 20 misioneros de la Fraternidade y de la Red-Luz Paraguay visitaron, durante 14 d\u00edas, tres comunidades ind\u00edgenas del Alto Paran\u00e1, llevando apoyo m\u00e9dico, odontol\u00f3gico, emocional, espiritual y material.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-77697 gallery-columns-2 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"missao_paraguai_sexto_encontro_02\" data-caption=\"\" href='https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_02.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_02-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_02-200x112.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_02-300x169.jpg 300w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_02-400x225.jpg 400w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_02-600x337.jpg 600w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_02.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-rel=\"iLightbox[postimages]\" data-title=\"missao_paraguai_sexto_encontro_05\" data-caption=\"\" href='https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_05.jpg'><img decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_05-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_05-200x112.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_05-300x169.jpg 300w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_05-400x225.jpg 400w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_05-600x337.jpg 600w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_05.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>El grupo Red-Luz del Paraguay llev\u00f3 a cabo el Sexto Encuentro de la Misi\u00f3n Paraguay \u201cDespertando Semillas\u201d, en uni\u00f3n con [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":77674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173,105,120],"tags":[2902,97],"class_list":["post-77697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","category-noticias-de-las-misiones","category-red-luz-es","tag-mision-paraguay","tag-servicio-humanitario-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v21.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena<\/title>\n<meta name=\"description\" content=\"Participaron 17 voluntarios de Paraguay, Argentina y Brasil. En dos comunidades, prestaron asistencia m\u00e9dica, veterinaria y entregaron donaciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena\" \/>\n<meta property=\"og:description\" content=\"Participaron 17 voluntarios de Paraguay, Argentina y Brasil. En dos comunidades, prestaron asistencia m\u00e9dica, veterinaria y entregaron donaciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/\" \/>\n<meta property=\"og:site_name\" content=\"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fraternidadehumanitaria\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-02T18:52:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Redator Espanhol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fraternidadeFHI\" \/>\n<meta name=\"twitter:site\" content=\"@fraternidadeFHI\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Redator Espanhol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/\",\"url\":\"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/\",\"name\":\"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena\",\"isPartOf\":{\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#website\"},\"datePublished\":\"2018-04-02T18:52:48+00:00\",\"dateModified\":\"2018-04-02T18:52:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28\"},\"description\":\"Participaron 17 voluntarios de Paraguay, Argentina y Brasil. En dos comunidades, prestaron asistencia m\u00e9dica, veterinaria y entregaron donaciones.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.fraterinternacional.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#website\",\"url\":\"https:\/\/www.fraterinternacional.org\/es\/\",\"name\":\"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional\",\"description\":\"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fraterinternacional.org\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28\",\"name\":\"Sergio Redator Espanhol\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena","description":"Participaron 17 voluntarios de Paraguay, Argentina y Brasil. En dos comunidades, prestaron asistencia m\u00e9dica, veterinaria y entregaron donaciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/","og_locale":"es_ES","og_type":"article","og_title":"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena","og_description":"Participaron 17 voluntarios de Paraguay, Argentina y Brasil. En dos comunidades, prestaron asistencia m\u00e9dica, veterinaria y entregaron donaciones.","og_url":"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/","og_site_name":"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional","article_publisher":"https:\/\/www.facebook.com\/fraternidadehumanitaria","article_published_time":"2018-04-02T18:52:48+00:00","og_image":[{"width":690,"height":388,"url":"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2018\/04\/missao_paraguai_sexto_encontro_01.jpg","type":"image\/jpeg"}],"author":"Sergio Redator Espanhol","twitter_card":"summary_large_image","twitter_creator":"@fraternidadeFHI","twitter_site":"@fraternidadeFHI","twitter_misc":{"Escrito por":"Sergio Redator Espanhol","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/","url":"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/","name":"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena","isPartOf":{"@id":"https:\/\/www.fraterinternacional.org\/es\/#website"},"datePublished":"2018-04-02T18:52:48+00:00","dateModified":"2018-04-02T18:52:48+00:00","author":{"@id":"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28"},"description":"Participaron 17 voluntarios de Paraguay, Argentina y Brasil. En dos comunidades, prestaron asistencia m\u00e9dica, veterinaria y entregaron donaciones.","breadcrumb":{"@id":"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraterinternacional.org\/es\/mision-paraguay-concreto-sexto-encuentro-con-consciencia-indigena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.fraterinternacional.org\/es\/"},{"@type":"ListItem","position":2,"name":"Misi\u00f3n Paraguay concret\u00f3 el sexto encuentro con la Consciencia Ind\u00edgena"}]},{"@type":"WebSite","@id":"https:\/\/www.fraterinternacional.org\/es\/#website","url":"https:\/\/www.fraterinternacional.org\/es\/","name":"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional","description":"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraterinternacional.org\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28","name":"Sergio Redator Espanhol"}]}},"_links":{"self":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/posts\/77697"}],"collection":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/comments?post=77697"}],"version-history":[{"count":0,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/posts\/77697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/media\/77674"}],"wp:attachment":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/media?parent=77697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/categories?post=77697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/tags?post=77697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}