{"id":15741,"date":"2016-04-09T13:14:40","date_gmt":"2016-04-09T16:14:40","guid":{"rendered":"http:\/\/www.fraterinternacional.org\/es\/?p=15741"},"modified":"2016-11-01T19:25:27","modified_gmt":"2016-11-01T22:25:27","slug":"peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte","status":"publish","type":"post","link":"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/","title":{"rendered":"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Mae-Divina_1.jpg\" rel=\"attachment wp-att-15730\"><img decoding=\"async\" class=\"alignright size-medium wp-image-15730\" src=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Mae-Divina_1-300x169.jpg\" alt=\"BH_Mae Divina_1\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Mae-Divina_1-200x113.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Mae-Divina_1.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El <a href=\"\/?page_id=76\">N\u00facleo-Luz<\/a> de Figueira en Belo Horizonte \u201cSagrado Cielo\u201d, afiliado a la <strong>Fraternidade \u2013 Federaci\u00f3n Humanitaria Internacional<\/strong>, organiza para el domingo 10 de abril un gran Encuentro de Confraternizaci\u00f3n entre peregrinos devotos de Mar\u00eda. El evento se realizar\u00e1 en la Casa de los Ni\u00f1os, extensi\u00f3n del citado n\u00facleo-luz, ubicado en la Avenida Mem de S\u00e1, 617, Santa Efig\u00eania, Belo Horizonte. La actividad cuenta con el apoyo del Monasterio Puerta de la Divina Misericordia, perteneciente a la <a href=\"http:\/\/wp.me\/P6GSxW-1If\">Orden Gracia Misericordia<\/a>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Nucleo003.jpg\" rel=\"attachment wp-att-15734\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-15734\" src=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Nucleo003-300x200.jpg\" alt=\"BH_Nucleo003\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Nucleo003-200x133.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Nucleo003.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u201cEl objetivo es dar un renovado impulso al grupo de peregrinos que desde la primera aparici\u00f3n de Mar\u00eda aqu\u00ed en el n\u00facleo de Belo Horizonte, el 11 de marzo de 2013, regularmente se re\u00fane todos los domingos en la Casa de los Ni\u00f1os, para orar, cantar y expresar toda su devoci\u00f3n a la Virgen Sant\u00edsima. Queremos celebrar entre todos, peregrinos y colaboradores, estos tres a\u00f1os de trabajo de oraci\u00f3n\u201d, explic\u00f3 Beth Picorelli, integrante de la junta coordinadora del N\u00facleo-Luz de Figueira en Belo Horizonte.<\/p>\n<p style=\"text-align: justify;\">Dijo que el evento, que comenzar\u00e1 a las 14.00 horas, es de car\u00e1cter abierto para todos los que deseen participar de un momento de uni\u00f3n con Cristo y Mar\u00eda. \u201cTodos los peregrinos pueden traer a familiares, amigos y conocidos\u201d.<\/p>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-overflow:visible;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div id=\"attachment_15724\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_3.jpg\" rel=\"attachment wp-att-15724\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15724\" class=\"size-medium wp-image-15724\" src=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_3-300x169.jpg\" alt=\"Encontro dominical na Casa das Crian\u00e7as\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_3-200x112.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_3-300x169.jpg 300w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_3-400x225.jpg 400w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_3-600x337.jpg 600w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_3.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-15724\" class=\"wp-caption-text\">Encuentro dominical en la Casa de los\u00a0Ni\u00f1os<\/p><\/div>\n<p style=\"text-align: justify;\">\u201cDespu\u00e9s de tres a\u00f1os de mantenerse viva la llama devocional de uni\u00f3n con nuestra Madre Divina, sentimos que era el momento de dar un nuevo impulso a ese grupo de peregrinos, que muchas veces venciendo dificultades de distancia f\u00edsica o de otra \u00edndole, pues varios de ellos vienen desde otras ciudades, permanece fiel y persistente a su compromiso interno con Mar\u00eda y asiste, domingo tras domingo, a la Casa de los Ni\u00f1os para realizar su trabajo de oraci\u00f3n y de contacto con la energ\u00eda mariana\u201d, destac\u00f3 el fray Thomas, coordinador del Monasterio Puerta de la Divina Misericordia, con sede en el N\u00facleo-Luz de Figueira en Belo Horizonte.<\/p>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div id=\"attachment_15721\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_2.jpg\" rel=\"attachment wp-att-15721\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15721\" class=\"size-medium wp-image-15721\" src=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_2-300x169.jpg\" alt=\"Os devotos comparecem de v\u00e1rias cidades de Minas Gerais\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_2-200x113.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_2-300x169.jpg 300w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_2-400x226.jpg 400w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_2-600x338.jpg 600w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_2.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-15721\" class=\"wp-caption-text\">Los\u00a0devotos acuden\u00a0desde diferentes ciudades<\/p><\/div>\n<p style=\"text-align: justify;\">Inform\u00f3 que durante el encuentro ser\u00e1 lanzado el proyecto de \u00f3mnibus peregrino, el cual, realizar\u00e1 visitas mensuales al <a href=\"\/?page_id=74\">Centro Mariano de Figueira<\/a>.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s informaciones pueden solicitarse al tel\u00e9fono (+55 &#8211; 31) 99645-9171 o al e-mail <a href=\"mailto:nucleobh@comunidadefigueira.org.br\">nucleobh@comunidadefigueira.org.br<\/a><\/p>\n<p>PROGRAMA<\/p>\n<p>&#8211; Coronilla de la Misericordia<\/p>\n<p>&#8211; Misterios del Rosario<\/p>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-no-min-height\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div id=\"attachment_15727\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_4.jpg\" rel=\"attachment wp-att-15727\"><img decoding=\"async\" aria-describedby=\"caption-attachment-15727\" class=\"wp-image-15727 size-medium\" src=\"http:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_4-300x169.jpg\" alt=\"BH_Casa das Criancas_Peregrinos_4\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_4-200x113.jpg 200w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_4-300x169.jpg 300w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_4-400x226.jpg 400w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_4-600x338.jpg 600w, https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Casa-das-Criancas_Peregrinos_4.jpg 690w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-15727\" class=\"wp-caption-text\">Varios peregrinos perseveran\u00a0hace 3 a\u00f1os<\/p><\/div>\n<p style=\"text-align: justify;\">&#8211; Presentaci\u00f3n del Coral del N\u00facleo-Luz de Figueira en Belo Horizonte<\/p>\n<p style=\"text-align: justify;\">&#8211; Filme: El Gran Milagro<\/p>\n<p style=\"text-align: justify;\">&#8211; Anuncio del nuevo ciclo de trabajo y espacio para preguntas de los peregrinos<\/p>\n<p style=\"text-align: justify;\">&#8211; Lunch de confraternizaci\u00f3n y celebraci\u00f3n de los 3 a\u00f1os de trabajo de oraci\u00f3n en la Casa de los Ni\u00f1os<\/p>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El N\u00facleo-Luz de Figueira en Belo Horizonte \u201cSagrado Cielo\u201d, afiliado a la Fraternidade \u2013 Federaci\u00f3n Humanitaria Internacional, organiza para el [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":15732,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[98,122],"class_list":["post-15741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia","tag-nucleos-luz-es","tag-vida-de-oracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v21.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte -<\/title>\n<meta name=\"description\" content=\"N\u00facleo-Luz en Belo Horizonte organiza encuentro de confraternizaci\u00f3n entre peregrinos devotos de Mar\u00eda para celebrar tres a\u00f1os de jornadas de oraci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte\" \/>\n<meta property=\"og:description\" content=\"N\u00facleo-Luz en Belo Horizonte organiza encuentro de confraternizaci\u00f3n entre peregrinos devotos de Mar\u00eda para celebrar tres a\u00f1os de jornadas de oraci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/\" \/>\n<meta property=\"og:site_name\" content=\"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fraternidadehumanitaria\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-09T16:14:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-01T22:25:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Mae-Divina_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"169\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sergio Redator Espanhol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fraternidadeFHI\" \/>\n<meta name=\"twitter:site\" content=\"@fraternidadeFHI\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Redator Espanhol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/\",\"url\":\"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/\",\"name\":\"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte -\",\"isPartOf\":{\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#website\"},\"datePublished\":\"2016-04-09T16:14:40+00:00\",\"dateModified\":\"2016-11-01T22:25:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28\"},\"description\":\"N\u00facleo-Luz en Belo Horizonte organiza encuentro de confraternizaci\u00f3n entre peregrinos devotos de Mar\u00eda para celebrar tres a\u00f1os de jornadas de oraci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.fraterinternacional.org\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#website\",\"url\":\"https:\/\/www.fraterinternacional.org\/es\/\",\"name\":\"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional\",\"description\":\"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fraterinternacional.org\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28\",\"name\":\"Sergio Redator Espanhol\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte -","description":"N\u00facleo-Luz en Belo Horizonte organiza encuentro de confraternizaci\u00f3n entre peregrinos devotos de Mar\u00eda para celebrar tres a\u00f1os de jornadas de oraci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/","og_locale":"es_ES","og_type":"article","og_title":"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte","og_description":"N\u00facleo-Luz en Belo Horizonte organiza encuentro de confraternizaci\u00f3n entre peregrinos devotos de Mar\u00eda para celebrar tres a\u00f1os de jornadas de oraci\u00f3n.","og_url":"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/","og_site_name":"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional","article_publisher":"https:\/\/www.facebook.com\/fraternidadehumanitaria","article_published_time":"2016-04-09T16:14:40+00:00","article_modified_time":"2016-11-01T22:25:27+00:00","og_image":[{"width":300,"height":169,"url":"https:\/\/www.fraterinternacional.org\/wp-content\/uploads\/2016\/04\/BH_Mae-Divina_1.jpg","type":"image\/jpeg"}],"author":"Sergio Redator Espanhol","twitter_card":"summary_large_image","twitter_creator":"@fraternidadeFHI","twitter_site":"@fraternidadeFHI","twitter_misc":{"Escrito por":"Sergio Redator Espanhol","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/","url":"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/","name":"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte -","isPartOf":{"@id":"https:\/\/www.fraterinternacional.org\/es\/#website"},"datePublished":"2016-04-09T16:14:40+00:00","dateModified":"2016-11-01T22:25:27+00:00","author":{"@id":"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28"},"description":"N\u00facleo-Luz en Belo Horizonte organiza encuentro de confraternizaci\u00f3n entre peregrinos devotos de Mar\u00eda para celebrar tres a\u00f1os de jornadas de oraci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fraterinternacional.org\/es\/peregrinos-devotos-de-maria-celebraran-tres-anos-de-encuentros-en-belo-horizonte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.fraterinternacional.org\/es\/"},{"@type":"ListItem","position":2,"name":"Peregrinos devotos de Mar\u00eda celebrar\u00e1n tres a\u00f1os de encuentros de oraci\u00f3n en Belo Horizonte"}]},{"@type":"WebSite","@id":"https:\/\/www.fraterinternacional.org\/es\/#website","url":"https:\/\/www.fraterinternacional.org\/es\/","name":"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional","description":"Fraternidade - Federa\u00e7\u00e3o Humanit\u00e1ria Internacional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fraterinternacional.org\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fraterinternacional.org\/es\/#\/schema\/person\/cf24d3eac28b0e09714ecb8cbd865c28","name":"Sergio Redator Espanhol"}]}},"_links":{"self":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/posts\/15741"}],"collection":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/comments?post=15741"}],"version-history":[{"count":0,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/posts\/15741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/media\/15732"}],"wp:attachment":[{"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/media?parent=15741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/categories?post=15741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fraterinternacional.org\/es\/wp-json\/wp\/v2\/tags?post=15741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}